{"id":7812,"name":"Arlene Mendoza","url":"https:\/\/www.instagram.com\/_arleneme_\/","description":"Soy fot\u00f3grafa mexicana, hago retratos de mujeres, fusionando belleza femenina con toques oscuros y conceptuales. Mi trabajo explora la feminidad de manera \u00fanica.","link":"https:\/\/errr-magazine.com\/english\/author\/dominekiraphoto\/","slug":"dominekiraphoto","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=24&d=identicon&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=48&d=identicon&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g"},"meta":{"jetpack_donation_warning_dismissed":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arlene Mendoza, autor en ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/author\/dominekiraphoto\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Arlene Mendoza, autor en ERRR MAGAZINE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/author\/dominekiraphoto\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=500&d=identicon&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/author\\\/dominekiraphoto\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/author\\\/dominekiraphoto\\\/\",\"name\":\"Arlene Mendoza, autor en ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/author\\\/dominekiraphoto\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/author\\\/dominekiraphoto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/author\\\/dominekiraphoto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/errr-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivo de Arlene Mendoza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/db16ffd08ad5c7d7af1b703882400824\",\"name\":\"Arlene Mendoza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g\",\"caption\":\"Arlene Mendoza\"},\"description\":\"Soy fot\u00f3grafa mexicana, hago retratos de mujeres, fusionando belleza femenina con toques oscuros y conceptuales. Mi trabajo explora la feminidad de manera \u00fanica.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/_arleneme_\\\/\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/author\\\/dominekiraphoto\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arlene Mendoza, autor en ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/author\/dominekiraphoto\/","og_locale":"en_US","og_type":"profile","og_title":"Arlene Mendoza, autor en ERRR MAGAZINE","og_url":"https:\/\/errr-magazine.com\/english\/author\/dominekiraphoto\/","og_site_name":"ERRR MAGAZINE","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=500&d=identicon&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/errr-magazine.com\/author\/dominekiraphoto\/","url":"https:\/\/errr-magazine.com\/author\/dominekiraphoto\/","name":"Arlene Mendoza, autor en ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"breadcrumb":{"@id":"https:\/\/errr-magazine.com\/author\/dominekiraphoto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/author\/dominekiraphoto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/errr-magazine.com\/author\/dominekiraphoto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/errr-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Archivo de Arlene Mendoza"}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/db16ffd08ad5c7d7af1b703882400824","name":"Arlene Mendoza","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2e4a72bb0ff09b2680cf4bd33bb64caf2ca9b11bfd0fed12ea6df33d890b700?s=96&d=identicon&r=g","caption":"Arlene Mendoza"},"description":"Soy fot\u00f3grafa mexicana, hago retratos de mujeres, fusionando belleza femenina con toques oscuros y conceptuales. Mi trabajo explora la feminidad de manera \u00fanica.","sameAs":["https:\/\/www.instagram.com\/_arleneme_\/"],"mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/author\/dominekiraphoto\/"}}]}},"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/7812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users"}]}}