{"id":192752,"date":"2025-09-06T11:40:50","date_gmt":"2025-09-06T17:40:50","guid":{"rendered":"https:\/\/errr-magazine.com\/?p=192752"},"modified":"2026-06-09T05:27:59","modified_gmt":"2026-06-09T11:27:59","slug":"temporada-de-peras","status":"publish","type":"post","link":"https:\/\/errr-magazine.com\/english\/temporada-de-peras\/","title":{"rendered":"Pear season"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>How did the idea for this book come about?<br><\/strong>No fue una idea que tuve a priori, fue algo que empez\u00f3 a ocurrir. Me fui a vivir al rancho de la abuela de una amiga. \u00c9ramos cinco personas y m\u00e1s de veinte animales. Era temporada seca. El poemario fue apareciendo en el d\u00eda a d\u00eda de la convivencia, a partir de las notas que tomaba en mi cuaderno, notas breves que no ten\u00edan otra intenci\u00f3n que registrar mi vida cotidiana, pero que se fueron transformando en poemas porque las im\u00e1genes insist\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>What did you discover in the process of writing it that you didn't imagine at the beginning?<br><\/strong>El universo del poemario termin\u00f3 ampli\u00e1ndose m\u00e1s de lo que pensaba, en el sentido de que las anotaciones desde el rancho empezaron a dar lugar a otros poemas sobre mi abuela y mi madre o sobre el mar Mediterr\u00e1neo. Como si el estado de presencia en el que me sent\u00eda hubiera abierto ciertas fisuras por las que empezaron a entrar los recuerdos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 partes tuvieron que quedarse fuera para que el libro\u00a0quedara\u00a0como est\u00e1?<\/strong><br>Hubo varios poemas que terminaron qued\u00e1ndose fuera porque no estaban listos, se hab\u00edan quedado muy pegados al registro inicial, no hab\u00edan evolucionado. Me di cuenta de que estaban ah\u00ed por un apego personal m\u00e1s que porque fueran parte del viaje del libro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>What conversations, readings, images, or sounds came into play during the writing of this book?<br><\/strong>Recuerdo vagamente que en esa \u00e9poca le\u00ed a poetas como <a href=\"https:\/\/www.instagram.com\/mariagomezlara10\/\"><strong>Mar\u00eda G\u00f3mez Lara<\/strong><\/a> o narradoras como <a href=\"https:\/\/www.elem.mx\/autor\/datos\/25336\"><strong>Tununa Mercado<\/strong><\/a>, pero lo que m\u00e1s me afect\u00f3 fueron las conversaciones con las personas con las que conviv\u00ed y los gestos de los animales: sobre todo de uno, el perro P\u00e3ngo, mi gran compa\u00f1ero de paseos.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"585\" height=\"1024\" data-src=\"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/temporada.png?resize=585%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-192758 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/temporada.png?resize=585%2C1024&amp;ssl=1 585w, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/temporada.png?resize=171%2C300&amp;ssl=1 171w, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/temporada.png?w=600&amp;ssl=1 600w\" data-sizes=\"(max-width: 585px) 100vw, 585px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 585px; --smush-placeholder-aspect-ratio: 585\/1024;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si pienso en un sonido, es el del viento previo a la helada o el del balido de las ovejas por la ma\u00f1ana. Si pienso en una imagen, la cumbre del Popocat\u00e9petl\u00a0a lo lejos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfHay una emoci\u00f3n o pregunta que lo\u00a0atraviese\u00a0de principio a fin?<br><\/strong>Una gratitud enorme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was there a moment when you felt the book changed direction?<br><\/strong>Fueron cambios peque\u00f1os a lo largo de los a\u00f1os. Se termin\u00f3 publicando tres a\u00f1os despu\u00e9s de lo previsto porque cambi\u00f3 de editorial y hubo otros imprevistos: esto hizo que lo releyera y lo corrigiera varias veces, pero nunca fue un cambio de rumbo abrupto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>How did your way of reading or watching change after you finished it?<br><\/strong>Supongo que me relaj\u00e9 un poco, como si el coraz\u00f3n pesara\u00a0menos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9\u00a0autorxs\u00a0te inspiran \u00faltimamente y qu\u00e9 encuentras en su forma de escribir?<\/strong><br>Por trabajo leo todos los d\u00edas y muy intensamente, as\u00ed que me nace m\u00e1s pensar qu\u00e9 lecturas siguen conmigo a pesar del tiempo y por qu\u00e9. Una de ellas es <a href=\"https:\/\/www.instagram.com\/labestiaser\/\"><strong>Susana Villalba<\/strong><\/a>. Leerla siempre me recuerda qu\u00e9 es para m\u00ed la poes\u00eda: una manera de crear relaciones inusitadas entre el lenguaje y la realidad.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/joelheimphoto\/\">Retrato por Joel Heim<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>The collection of poems began to emerge in the day-to-day life of our lives, from the notes I took in my notebook, brief notes that had no other intention than to record my daily life, but which gradually transformed into poems because the images persisted.<\/p>","protected":false},"author":7137,"featured_media":192753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17849],"tags":[],"class_list":["post-192752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviews"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temporada de peras - ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/temporada-de-peras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temporada de peras - ERRR MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"El poemario fue apareciendo en el d\u00eda a d\u00eda de la convivencia, a partir de las notas que tomaba en mi cuaderno, notas breves que no ten\u00edan otra intenci\u00f3n que registrar mi vida cotidiana, pero que se fueron transformando en poemas porque las im\u00e1genes insist\u00edan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/temporada-de-peras\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-06T17:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T11:27:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carla Sant\u00e1ngelo L\u00e1zaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carla Sant\u00e1ngelo L\u00e1zaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/\"},\"author\":{\"name\":\"Carla Sant\u00e1ngelo L\u00e1zaro\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/a939f9cbf01a537ed36ee135d3700439\"},\"headline\":\"Temporada de peras\",\"datePublished\":\"2025-09-06T17:40:50+00:00\",\"dateModified\":\"2026-06-09T11:27:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/\"},\"wordCount\":524,\"image\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1704758365482.jpeg?fit=800%2C800&ssl=1\",\"articleSection\":[\"Interviews\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/\",\"name\":\"Temporada de peras - ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1704758365482.jpeg?fit=800%2C800&ssl=1\",\"datePublished\":\"2025-09-06T17:40:50+00:00\",\"dateModified\":\"2026-06-09T11:27:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/a939f9cbf01a537ed36ee135d3700439\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1704758365482.jpeg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1704758365482.jpeg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/temporada-de-peras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/errr-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporada de peras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/a939f9cbf01a537ed36ee135d3700439\",\"name\":\"Carla Sant\u00e1ngelo L\u00e1zaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08e1511632ac655c22a06dd4fc26becde5211671331ae2069f9ab906cfb86e90?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08e1511632ac655c22a06dd4fc26becde5211671331ae2069f9ab906cfb86e90?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08e1511632ac655c22a06dd4fc26becde5211671331ae2069f9ab906cfb86e90?s=96&d=identicon&r=g\",\"caption\":\"Carla Sant\u00e1ngelo L\u00e1zaro\"},\"description\":\"Doctoranda en Estudios filol\u00f3gicos en la Universidad de Sevilla, donde investiga la relaci\u00f3n entre literatura, exilio y perspectiva de g\u00e9nero. Es autora de los poemarios Liquen (Aguaviva Ediciones, 2021), pedres i vent (Ediciones en el mar, 2023) y Temporada de peras (Cicely Editorial, 2024).\",\"sameAs\":[\"https:\\\/\\\/carlasantangelo.com\"],\"url\":\"https:\\\/\\\/errr-magazine.com\\\/english\\\/author\\\/csantangelolazaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temporada de peras - ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/temporada-de-peras\/","og_locale":"en_US","og_type":"article","og_title":"Temporada de peras - ERRR MAGAZINE","og_description":"El poemario fue apareciendo en el d\u00eda a d\u00eda de la convivencia, a partir de las notas que tomaba en mi cuaderno, notas breves que no ten\u00edan otra intenci\u00f3n que registrar mi vida cotidiana, pero que se fueron transformando en poemas porque las im\u00e1genes insist\u00edan.","og_url":"https:\/\/errr-magazine.com\/english\/temporada-de-peras\/","og_site_name":"ERRR MAGAZINE","article_published_time":"2025-09-06T17:40:50+00:00","article_modified_time":"2026-06-09T11:27:59+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg","type":"image\/jpeg"}],"author":"Carla Sant\u00e1ngelo L\u00e1zaro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Carla Sant\u00e1ngelo L\u00e1zaro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#article","isPartOf":{"@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/"},"author":{"name":"Carla Sant\u00e1ngelo L\u00e1zaro","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/a939f9cbf01a537ed36ee135d3700439"},"headline":"Temporada de peras","datePublished":"2025-09-06T17:40:50+00:00","dateModified":"2026-06-09T11:27:59+00:00","mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/"},"wordCount":524,"image":{"@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg?fit=800%2C800&ssl=1","articleSection":["Interviews"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/","url":"https:\/\/errr-magazine.com\/temporada-de-peras\/","name":"Temporada de peras - ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#primaryimage"},"image":{"@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg?fit=800%2C800&ssl=1","datePublished":"2025-09-06T17:40:50+00:00","dateModified":"2026-06-09T11:27:59+00:00","author":{"@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/a939f9cbf01a537ed36ee135d3700439"},"breadcrumb":{"@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/temporada-de-peras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#primaryimage","url":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg?fit=800%2C800&ssl=1","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/errr-magazine.com\/temporada-de-peras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/errr-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Temporada de peras"}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/a939f9cbf01a537ed36ee135d3700439","name":"Carla Sant\u00e1ngelo L\u00e1zaro","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/08e1511632ac655c22a06dd4fc26becde5211671331ae2069f9ab906cfb86e90?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08e1511632ac655c22a06dd4fc26becde5211671331ae2069f9ab906cfb86e90?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08e1511632ac655c22a06dd4fc26becde5211671331ae2069f9ab906cfb86e90?s=96&d=identicon&r=g","caption":"Carla Sant\u00e1ngelo L\u00e1zaro"},"description":"PhD candidate in Philological Studies at the University of Seville, where she researches the relationship between literature, exile and gender perspective. She is the author of the poetry collections Liquen (Aguaviva Ediciones, 2021), pedres i vent (Ediciones en el mar, 2023) and Temporada de peras (Cicely Editorial, 2024).","sameAs":["https:\/\/carlasantangelo.com"],"url":"https:\/\/errr-magazine.com\/english\/author\/csantangelolazaro\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2025\/09\/1704758365482.jpeg?fit=800%2C800&ssl=1","mfb_rest_fields":["title","yoast_head","yoast_head_json","jetpack_sharing_enabled","jetpack_featured_media_url"],"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/192752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/7137"}],"replies":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/comments?post=192752"}],"version-history":[{"count":4,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/192752\/revisions"}],"predecessor-version":[{"id":192760,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/192752\/revisions\/192760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media\/192753"}],"wp:attachment":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media?parent=192752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/categories?post=192752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/tags?post=192752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}