{"id":177478,"date":"2022-08-30T21:42:16","date_gmt":"2022-08-31T02:42:16","guid":{"rendered":"https:\/\/errr-magazine.com\/?p=177478"},"modified":"2026-06-10T11:03:31","modified_gmt":"2026-06-10T17:03:31","slug":"177478-2","status":"publish","type":"post","link":"https:\/\/errr-magazine.com\/english\/177478-2\/","title":{"rendered":""},"content":{"rendered":"<p>Saberse piedra<br \/>\n(golpes antiguos en lo profundo de la tierra)<br \/>\nor<br \/>\nSaberse vidrio<br \/>\n(reflejos de otras verdades con o sin luz)<br \/>\nand <\/p>\n<p>de esta fr\u00e1gil<br \/>\ninteracci\u00f3n en<br \/>\nlos t\u00e9rminos<br \/>\nrompi\u00e9ndose<br \/>\nentre s\u00ed<br \/>\ndesencadenan verbos<br \/>\nque ser\u00e1n<br \/>\nsepultados<br \/>\nya<br \/>\naqu\u00ed:<\/p>\n<p>volando bajo<br \/>\nquem\u00e1ndose las alas<br \/>\nel p\u00e1jaro muere<br \/>\nlejos<br \/>\nde su hogar<\/p>\n<p>llega el zopilote<br \/>\ny canta la descomposici\u00f3n<br \/>\ndice que esta muerte y que esta vida&#8230;<\/p>\n<p>pero el p\u00e1jaro ya no est\u00e1 <\/p>\n<p>Decir que esto es algo no tendr\u00e1 ning\u00fan efecto hasta que el tiempo haga lo suyo. S\u00e9pase aqu\u00ed la sentencia. El calor inmundo me retuerce la memoria y no quiero m\u00e1s que esfumarme en la eternidad del humo espeso de un vaporizador, aceite hirviendo en la sangre en el cerebro la visi\u00f3n se me vuelve ensue\u00f1o se me vuelve voz intoxicada clamando absurdas canciones madrugada atascada en la garganta. El ruido interminable de afuera. Tengo qu\u00e9 comer para no morirme de hambre. Hablando de vitalidad me viene a la conciencia el amor. \u00bfQu\u00e9 tan lejos est\u00e1s? Ladrar con los perros hasta que el sol calcine mis ganas de volver a verte. <\/p>","protected":false},"excerpt":{"rendered":"<p>Saberse piedra (golpes antiguos en lo profundo de la tierra) o Saberse vidrio (reflejos de otras verdades con o sin luz) y de esta fr\u00e1gil interacci\u00f3n en los t\u00e9rminos rompi\u00e9ndose entre s\u00ed desencadenan verbos que ser\u00e1n sepultados ya aqu\u00ed: volando bajo quem\u00e1ndose las alas el p\u00e1jaro muere lejos de su hogar llega el zopilote y [&hellip;]<\/p>\n","protected":false},"author":5411,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17385],"tags":[],"class_list":["post-177478","post","type-post","status-publish","format-standard","hentry","category-writing"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/177478-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- ERRR MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"Saberse piedra (golpes antiguos en lo profundo de la tierra) o Saberse vidrio (reflejos de otras verdades con o sin luz) y de esta fr\u00e1gil interacci\u00f3n en los t\u00e9rminos rompi\u00e9ndose entre s\u00ed desencadenan verbos que ser\u00e1n sepultados ya aqu\u00ed: volando bajo quem\u00e1ndose las alas el p\u00e1jaro muere lejos de su hogar llega el zopilote y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/177478-2\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T02:42:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T17:03:31+00:00\" \/>\n<meta name=\"author\" content=\"Mart\u00edn Avechuco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@_martinavechuco\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mart\u00edn Avechuco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/177478-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/177478-2\\\/\"},\"author\":{\"name\":\"Mart\u00edn Avechuco\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/13c7184ce6284726f31c1c89d0aa5380\"},\"headline\":\"No title\",\"datePublished\":\"2022-08-31T02:42:16+00:00\",\"dateModified\":\"2026-06-10T17:03:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/177478-2\\\/\"},\"wordCount\":198,\"articleSection\":[\"Writing\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/177478-2\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/177478-2\\\/\",\"name\":\"- ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"datePublished\":\"2022-08-31T02:42:16+00:00\",\"dateModified\":\"2026-06-10T17:03:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/13c7184ce6284726f31c1c89d0aa5380\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/177478-2\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/13c7184ce6284726f31c1c89d0aa5380\",\"name\":\"Mart\u00edn Avechuco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4362a2fa296b823b12f3f49b9808fee3d8a1c70e278cd5e710b71668094beaa7?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4362a2fa296b823b12f3f49b9808fee3d8a1c70e278cd5e710b71668094beaa7?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4362a2fa296b823b12f3f49b9808fee3d8a1c70e278cd5e710b71668094beaa7?s=96&d=identicon&r=g\",\"caption\":\"Mart\u00edn Avechuco\"},\"description\":\"blablabla\",\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/_martinavechuco\",\"https:\\\/\\\/www.instagram.com\\\/martinavechuco\\\/\",\"https:\\\/\\\/x.com\\\/_martinavechuco\"],\"url\":\"https:\\\/\\\/errr-magazine.com\\\/english\\\/author\\\/_martinavechuco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/177478-2\/","og_locale":"en_US","og_type":"article","og_title":"- ERRR MAGAZINE","og_description":"Saberse piedra (golpes antiguos en lo profundo de la tierra) o Saberse vidrio (reflejos de otras verdades con o sin luz) y de esta fr\u00e1gil interacci\u00f3n en los t\u00e9rminos rompi\u00e9ndose entre s\u00ed desencadenan verbos que ser\u00e1n sepultados ya aqu\u00ed: volando bajo quem\u00e1ndose las alas el p\u00e1jaro muere lejos de su hogar llega el zopilote y [&hellip;]","og_url":"https:\/\/errr-magazine.com\/english\/177478-2\/","og_site_name":"ERRR MAGAZINE","article_published_time":"2022-08-31T02:42:16+00:00","article_modified_time":"2026-06-10T17:03:31+00:00","author":"Mart\u00edn Avechuco","twitter_card":"summary_large_image","twitter_creator":"@_martinavechuco","twitter_misc":{"Written by":"Mart\u00edn Avechuco","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/errr-magazine.com\/177478-2\/#article","isPartOf":{"@id":"https:\/\/errr-magazine.com\/177478-2\/"},"author":{"name":"Mart\u00edn Avechuco","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/13c7184ce6284726f31c1c89d0aa5380"},"headline":"No title","datePublished":"2022-08-31T02:42:16+00:00","dateModified":"2026-06-10T17:03:31+00:00","mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/177478-2\/"},"wordCount":198,"articleSection":["Writing"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/errr-magazine.com\/177478-2\/","url":"https:\/\/errr-magazine.com\/177478-2\/","name":"- ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"datePublished":"2022-08-31T02:42:16+00:00","dateModified":"2026-06-10T17:03:31+00:00","author":{"@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/13c7184ce6284726f31c1c89d0aa5380"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/177478-2\/"]}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/13c7184ce6284726f31c1c89d0aa5380","name":"Martin Avechuco","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4362a2fa296b823b12f3f49b9808fee3d8a1c70e278cd5e710b71668094beaa7?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4362a2fa296b823b12f3f49b9808fee3d8a1c70e278cd5e710b71668094beaa7?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4362a2fa296b823b12f3f49b9808fee3d8a1c70e278cd5e710b71668094beaa7?s=96&d=identicon&r=g","caption":"Mart\u00edn Avechuco"},"description":"blablabla","sameAs":["https:\/\/twitter.com\/_martinavechuco","https:\/\/www.instagram.com\/martinavechuco\/","https:\/\/x.com\/_martinavechuco"],"url":"https:\/\/errr-magazine.com\/english\/author\/_martinavechuco\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","mfb_rest_fields":["title","yoast_head","yoast_head_json","jetpack_sharing_enabled","jetpack_featured_media_url"],"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/177478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/5411"}],"replies":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/comments?post=177478"}],"version-history":[{"count":3,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/177478\/revisions"}],"predecessor-version":[{"id":177490,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/177478\/revisions\/177490"}],"wp:attachment":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media?parent=177478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/categories?post=177478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/tags?post=177478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}