{"id":147763,"date":"2019-10-27T15:45:36","date_gmt":"2019-10-27T04:45:36","guid":{"rendered":"http:\/\/errr-magazine.com\/?p=147763"},"modified":"2022-08-31T01:30:01","modified_gmt":"2022-08-31T06:30:01","slug":"elixir-neon","status":"publish","type":"post","link":"https:\/\/errr-magazine.com\/english\/elixir-neon\/","title":{"rendered":"Elixir ne\u00f3n"},"content":{"rendered":"<p>\u00bfHasta cu\u00e1ndo vamos a abrir los ojos; los del coraz\u00f3n, los del interior y los del esp\u00edritu?<\/p>\n<p>Nos han distorsionado el concepto de felicidad por un largo periodo, implantado patrones y modelos a seguir.<\/p>\n<p>El tiempo, el entorno, las malas elecciones y la falta de amor propio, se han encargado de alterar toda la realidad. Incluso, el verdadero significado del amor.<\/p>\n<p>Hemos entregado tesoros a personas equivocadas, y hemos regalado momentos a individuos que no han valorado ninguno de estos.<\/p>\n<p>No todo est\u00e1 perdido&#8230; Pues no era ah\u00ed donde \u00edbamos a florecer, s\u00f3lo echamos ra\u00edz para en primavera poder resplandecer.<\/p>\n<p>A\u00fan cuando sintamos que hemos ido apresurados, aferr\u00e1ndonos a que el coraz\u00f3n se diera prisa; no hemos llegado tarde a ning\u00fan lugar, nadie nunca aparece anticipadamente y nunca nadie ni nada, a deshora&#8230;<\/p>\n<p>La sal del mar, me ha ido curando las heridas; con sus olas suaves me ha quitado la venda de los ojos; la brisa lentamente me ha susurrado que todo es a tiempo y a ritmo.<\/p>\n<p style=\"text-align: center\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Yo siempre he cre\u00eddo que el amor es una droga&#8230; pero todo\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0estupefaciente tiene un color y un sabor diferente.<\/p>\n<p>A\u00fan sostengo miedos que sembr\u00e9 en mi cuerpo.<\/p>\n<p>Cada vez que me invade un sentimiento de afecto, el querer confiar nuevamente, el deseo de dejarme llevar por este fuerte alucin\u00f3geno llamado amor; salgo corriendo. Trato de huir y esconderme en rincones donde nadie pueda encontrarme.<\/p>\n<p>En autom\u00e1tico, env\u00edo bloqueos a mi psiquis para que \u00e9ste los rechace. Es como una valla que nadie puede cruzar.<\/p>\n<p>Desconfianza de entregar mi coraz\u00f3n y alguien lo vuelva a lesionar.<\/p>\n<p style=\"text-align: center\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Pero, \u00bfQui\u00e9n no est\u00e1 tentado a probar nuevos elixires que produzcan un gran placer?<\/p>\n<p>Que yo no quiero un pr\u00edncipe azul, pues lo prefiero de un color m\u00e1s original y menos b\u00e1sico, y que no lo quiero tan pr\u00edncipe.<\/p>\n<p>Quiero algo real, tan real como yo.<\/p>\n<p>Sin usar los est\u00fapidos m\u00e9todos que la sociedad actual ha impuesto. Presentando desinter\u00e9s, buscando reemplazos y romances fugaces en aplicaciones vac\u00edas; que con tan s\u00f3lo un par de chats, se tienen en su cama sin inspirar a nada m\u00e1s; seduciendo al pr\u00f3jimo para en un par de semanas, botarle.<\/p>\n<p>Quiero ser con alguien transparente, trasl\u00facida, sin temor a naufragar en nuestras aguas. Que se emocione conmigo por las cosas que para los dem\u00e1s ojos, son simples: Un atardecer, una puesta de sol, una luna brillante, las luces de la ciudad, el olor y la tranquilidad a la orilla del mar.<\/p>\n<p>Quitarnos la ropa, las pretensiones, y las barreras que construimos por los desastres antes vividos.<\/p>\n<p>Bailar juntos, emborracharnos, y re\u00edr a carcajadas por nuestro trance constante.<\/p>\n<p>Hacer locuras cual ni\u00f1os, y contemplarnos uno al otro en cada paso avanzado.<\/p>\n<p>Montarnos en un cohete, viajando todo el tiempo a destinos que jam\u00e1s hayamos llegado. Munchear juntos, seducirnos con nuestras luces interiores, despertar sin ropa y sin pena.<\/p>\n<p>En cada beso, menos secretos; en cada caricia m\u00e1s uni\u00f3n, en cada orgasmo una total fusi\u00f3n de nuestras almas.<\/p>\n<p>Un d\u00eda a la vez, viviendo cada minuto como es.<\/p>\n<p>Hacer el amor sucio, bonito, rom\u00e1ntico, salvaje. Cada siempre en la intimidad, perdernos, encontrarnos y explotar juntos. Descubri\u00e9ndonos cada d\u00eda, escalando de la mano y llegando a todos nuestros l\u00edmites.<\/p>\n<p>Que nuestra morada sean nuestros cuerpos complement\u00e1ndose. El lugar donde nuestras almas puedan estar en total libertad.<\/p>\n<p>Quiero ser con alguien, sin doler.<\/p>\n<p>Porque ya no estamos en la \u00e9poca de tener amores mediocres, amores a medias.<\/p>\n<p>Estamos en el momento perfecto, para explotar de emociones, de amor, de magia y de puta felicidad.<\/p>\n<p>Photography by <a href=\"https:\/\/www.karinaphoto.net\/\">Karina Flores<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfHasta cu\u00e1ndo vamos a abrir los ojos; los del coraz\u00f3n, los del interior y los del esp\u00edritu? Nos han distorsionado el concepto de felicidad por un largo periodo, implantado patrones y modelos a seguir. El tiempo, el entorno, las malas elecciones y la falta de amor propio, se han encargado de alterar toda la realidad. [&hellip;]<\/p>\n","protected":false},"author":5141,"featured_media":150327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7997],"tags":[],"class_list":["post-147763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-textos"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elixir ne\u00f3n - ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/elixir-neon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elixir ne\u00f3n - ERRR MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"\u00bfHasta cu\u00e1ndo vamos a abrir los ojos; los del coraz\u00f3n, los del interior y los del esp\u00edritu? Nos han distorsionado el concepto de felicidad por un largo periodo, implantado patrones y modelos a seguir. El tiempo, el entorno, las malas elecciones y la falta de amor propio, se han encargado de alterar toda la realidad. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/elixir-neon\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-27T04:45:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T06:30:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1478\" \/>\n\t<meta property=\"og:image:height\" content=\"979\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Panrmm__\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Panrmm__\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/\"},\"author\":{\"name\":\"Panrmm__\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/9929f4dc1e3ede328bcc13dd1d227af4\"},\"headline\":\"Elixir ne\u00f3n\",\"datePublished\":\"2019-10-27T04:45:36+00:00\",\"dateModified\":\"2022-08-31T06:30:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/\"},\"wordCount\":639,\"image\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/edinburgh.jpg\",\"articleSection\":[\"Textos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/\",\"name\":\"Elixir ne\u00f3n - ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/edinburgh.jpg\",\"datePublished\":\"2019-10-27T04:45:36+00:00\",\"dateModified\":\"2022-08-31T06:30:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/9929f4dc1e3ede328bcc13dd1d227af4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/edinburgh.jpg\",\"contentUrl\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/edinburgh.jpg\",\"width\":1478,\"height\":979},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/elixir-neon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/errr-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elixir ne\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/9929f4dc1e3ede328bcc13dd1d227af4\",\"name\":\"Panrmm__\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d354fca88c7151a71def5c3ec0ab802d2d2514db40846586d87b85181b7995a0?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d354fca88c7151a71def5c3ec0ab802d2d2514db40846586d87b85181b7995a0?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d354fca88c7151a71def5c3ec0ab802d2d2514db40846586d87b85181b7995a0?s=96&d=identicon&r=g\",\"caption\":\"Panrmm__\"},\"description\":\"A escuchar a mi cuerpo y a mi coraz\u00f3n, lo que en ese momento necesite y quiera hacer, lo hago. (Es real, no tengo un trabajo fijo, porque s\u00e9 que siempre quiero volar a diferentes lugares). Viajo a la playa todo el tiempo, y a veces trabajo all\u00e1, de pronto en la ciudad; me la paso escribiendo y aprendiendo del hoy.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/panrmm__\\\/\"],\"url\":\"https:\\\/\\\/errr-magazine.com\\\/english\\\/author\\\/panrmm__\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elixir ne\u00f3n - ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/elixir-neon\/","og_locale":"en_US","og_type":"article","og_title":"Elixir ne\u00f3n - ERRR MAGAZINE","og_description":"\u00bfHasta cu\u00e1ndo vamos a abrir los ojos; los del coraz\u00f3n, los del interior y los del esp\u00edritu? Nos han distorsionado el concepto de felicidad por un largo periodo, implantado patrones y modelos a seguir. El tiempo, el entorno, las malas elecciones y la falta de amor propio, se han encargado de alterar toda la realidad. [&hellip;]","og_url":"https:\/\/errr-magazine.com\/english\/elixir-neon\/","og_site_name":"ERRR MAGAZINE","article_published_time":"2019-10-27T04:45:36+00:00","article_modified_time":"2022-08-31T06:30:01+00:00","og_image":[{"width":1478,"height":979,"url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg","type":"image\/jpeg"}],"author":"Panrmm__","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Panrmm__","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/errr-magazine.com\/elixir-neon\/#article","isPartOf":{"@id":"https:\/\/errr-magazine.com\/elixir-neon\/"},"author":{"name":"Panrmm__","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/9929f4dc1e3ede328bcc13dd1d227af4"},"headline":"Elixir ne\u00f3n","datePublished":"2019-10-27T04:45:36+00:00","dateModified":"2022-08-31T06:30:01+00:00","mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/elixir-neon\/"},"wordCount":639,"image":{"@id":"https:\/\/errr-magazine.com\/elixir-neon\/#primaryimage"},"thumbnailUrl":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg","articleSection":["Textos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/errr-magazine.com\/elixir-neon\/","url":"https:\/\/errr-magazine.com\/elixir-neon\/","name":"Elixir ne\u00f3n - ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/errr-magazine.com\/elixir-neon\/#primaryimage"},"image":{"@id":"https:\/\/errr-magazine.com\/elixir-neon\/#primaryimage"},"thumbnailUrl":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg","datePublished":"2019-10-27T04:45:36+00:00","dateModified":"2022-08-31T06:30:01+00:00","author":{"@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/9929f4dc1e3ede328bcc13dd1d227af4"},"breadcrumb":{"@id":"https:\/\/errr-magazine.com\/elixir-neon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/elixir-neon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/errr-magazine.com\/elixir-neon\/#primaryimage","url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg","contentUrl":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg","width":1478,"height":979},{"@type":"BreadcrumbList","@id":"https:\/\/errr-magazine.com\/elixir-neon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/errr-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Elixir ne\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/9929f4dc1e3ede328bcc13dd1d227af4","name":"Panrmm__","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d354fca88c7151a71def5c3ec0ab802d2d2514db40846586d87b85181b7995a0?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d354fca88c7151a71def5c3ec0ab802d2d2514db40846586d87b85181b7995a0?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d354fca88c7151a71def5c3ec0ab802d2d2514db40846586d87b85181b7995a0?s=96&d=identicon&r=g","caption":"Panrmm__"},"description":"To listen to my body and my heart, whatever I need and want to do at that moment, I do it. (It's real, I don't have a fixed job, because I know I always want to fly to different places). I travel to the beach all the time, and sometimes I work there, suddenly in the city; I spend my time writing and learning from today.","sameAs":["https:\/\/www.instagram.com\/panrmm__\/"],"url":"https:\/\/errr-magazine.com\/english\/author\/panrmm__\/"}]}},"jetpack_featured_media_url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2019\/10\/edinburgh.jpg","jetpack-related-posts":[{"id":204271,"url":"https:\/\/errr-magazine.com\/english\/el-hogar-llevaba-tu-nombre\/","url_meta":{"origin":147763,"position":0},"title":"Home had your name","author":"Azul Mv\u00e1","date":"04\/16\/2026","format":false,"excerpt":"Y ojal\u00e1 no tuviera tan roto el coraz\u00f3n, y ojal\u00e1 no hubieses sido t\u00fa, porque podr\u00edamos burlarnos de todos, podr\u00edamos huir de todo, podr\u00edamos correr sin mirar atr\u00e1s. Porque al final nunca \u00e9ramos nosotras dos; porque al final el hogar llevaba tu nombre; porque al final no hay nada como\u2026","rel":"","context":"In &quot;Narrativa&quot;","block_context":{"text":"Narrativa","link":"https:\/\/errr-magazine.com\/english\/category\/writing\/narrativa\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":203065,"url":"https:\/\/errr-magazine.com\/english\/la-vida-esta-hecha-de-duelos\/","url_meta":{"origin":147763,"position":1},"title":"Life Is Made of Grief","author":"Valeria Mar Trevi\u00f1o","date":"03\/25\/2026","format":false,"excerpt":"No one tells us that one of the worst kinds of death is the death of the worlds we build: the illusions, the stories we took as real, the futures we inhabited without even realizing it.","rel":"","context":"In &quot;Narrativa&quot;","block_context":{"text":"Narrativa","link":"https:\/\/errr-magazine.com\/english\/category\/writing\/narrativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-IMG_8375.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-IMG_8375.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-IMG_8375.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-IMG_8375.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":186131,"url":"https:\/\/errr-magazine.com\/english\/a-pedradas\/","url_meta":{"origin":147763,"position":2},"title":"A pedradas","author":"Isaac L\u00e1zaro","date":"10\/27\/2023","format":false,"excerpt":"Nadie me entren\u00f3 en el amor,nadie me dijo c\u00f3mo era,nunca alguien me ense\u00f1\u00f3\u00a0a soportar la indiferencia.No hubo alma que dijeralo que pasa cuandoel coraz\u00f3n se aprieta.Tuve que aprender a pedradas,por la v\u00eda del golpeque en ocasiones,casi siempre,se tira a matar\u00a0o se pierde.Nadie jam\u00e1s mencion\u00f3\u00a0que el coraz\u00f3n se rompe,que duele ver\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2023\/10\/51323662266_46b73fb704_k.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2023\/10\/51323662266_46b73fb704_k.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2023\/10\/51323662266_46b73fb704_k.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2023\/10\/51323662266_46b73fb704_k.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2023\/10\/51323662266_46b73fb704_k.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2023\/10\/51323662266_46b73fb704_k.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":145881,"url":"https:\/\/errr-magazine.com\/english\/aqui-2\/","url_meta":{"origin":147763,"position":3},"title":"Aqu\u00ed","author":"Yetla \u00c1lvarez","date":"08\/19\/2019","format":false,"excerpt":"Te fuiste y te llevaste contigo las sonrisas de todos nuestros buenos momentos, robaste mi coraz\u00f3n y te lo comiste a pedazos frente a mi, hurtaste mi forma de entregarme con locura al amor y la usaste tan solo para ti. Te ame desde el primer momento que te conoc\u00ed\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/07\/7-4.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/07\/7-4.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/07\/7-4.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/07\/7-4.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":159051,"url":"https:\/\/errr-magazine.com\/english\/sobre-la-muerte-y-otras-cosas\/","url_meta":{"origin":147763,"position":4},"title":"Sobre la muerte y otras cosas&#8230;","author":"Adriana Balderas","date":"05\/03\/2020","format":false,"excerpt":"No es que no sienta, es que respiro profundo y procuro poner una sonrisa en mi cara, siento que me salen mejor las cosas, mi d\u00eda mejora y me la llevo tranquila. No limito mis sentimientos, pero procuro que no me invadan durante las 24 hrs que tiene un d\u00eda.\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/05\/43845578410_5660b614e1_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/05\/43845578410_5660b614e1_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/05\/43845578410_5660b614e1_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/05\/43845578410_5660b614e1_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":158686,"url":"https:\/\/errr-magazine.com\/english\/nuestra-ultima-combustion-tu-recuerdo-y-yo\/","url_meta":{"origin":147763,"position":5},"title":"Nuestra \u00daltima Combusti\u00f3n (tu recuerdo y yo)","author":"Jorge G. Karam","date":"04\/28\/2020","format":false,"excerpt":"\"Half of what i sat is meaningless, but i say it just to reach you...\" -John Lennon Repentinamente hoy te record\u00e9. Lo hice con la canci\u00f3n con la cual indirectamente te despediste, la colgaste en tu muro de Facebook antes de borrarme con unas palabras que no recuerdo m\u00e1s que\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"mfb_rest_fields":["title","yoast_head","yoast_head_json","jetpack_featured_media_url","jetpack-related-posts","jetpack_sharing_enabled"],"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/147763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/5141"}],"replies":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/comments?post=147763"}],"version-history":[{"count":3,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/147763\/revisions"}],"predecessor-version":[{"id":150328,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/147763\/revisions\/150328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media\/150327"}],"wp:attachment":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media?parent=147763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/categories?post=147763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/tags?post=147763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}