{"id":139363,"date":"2018-11-05T10:39:09","date_gmt":"2018-11-04T23:39:09","guid":{"rendered":"http:\/\/errr-magazine.com\/?p=139363"},"modified":"2022-08-31T01:45:44","modified_gmt":"2022-08-31T06:45:44","slug":"la-desaparicion-del-helado","status":"publish","type":"post","link":"https:\/\/errr-magazine.com\/english\/la-desaparicion-del-helado\/","title":{"rendered":"La desaparici\u00f3n del Helado"},"content":{"rendered":"<p>\u00bfHab\u00edas probado alguna vez helado m\u00e1s perfecto? Karina lo hab\u00eda hecho, el mejor helado de yogurt de la ciudad. \u00bfCiudad? \u00a1Nah!, del estado, del pa\u00eds, del mundo. Pod\u00edas ponerle cuantos aditivos quisieras y la combinaci\u00f3n favorita de aquella peque\u00f1a f\u00e9mina era; kiwi al fondo, cereza en medio y galleta de chocolate hecha polvo como cobertura.<\/p>\n<p>Karina no ten\u00eda miedo de probar lo perfecto, \u00bft\u00fa lo tienes? Ella quiz\u00e1 ni siquiera lo sab\u00eda, se lo jambaba sin pensar, se deshac\u00eda en \u00e9l, restregaba su cuerpo, se derret\u00eda junto con \u00e9l. \u00bfConsecuencias? No, ella no pensaba en eso. Amar algo no deber\u00eda tener consecuencias, no malas por lo menos. Pero no era cualquier \u201calgo\u201d era PER-FEC-CI\u00d3N, el mejor helado del mundo, EL MUNDO. Y te advierto amigo, que si de algo deber\u00edas tener miedo, es de encontrar la perfecci\u00f3n y amarla. Ah s\u00ed, y Karina nunca ten\u00eda en mente que eso podr\u00eda acabar. Ja\u2019<\/p>\n<p>Y bueno, presientes lo que viene, lo s\u00e9 y tienes raz\u00f3n. Exacto, un d\u00eda como de costumbre Karina fue en busca de su tan apreciado helado, y bueno, lo que todos sospech\u00e1bamos, la tienda estaba cerrada,\u00a0 hab\u00eda trabajadores desmontando el espectacular de la helader\u00eda, de la mejor helader\u00eda del mundo, EL MUNDO\u2026 Karina no pudo guardar la calma, como era de esperarse. Y revent\u00f3 en llanto, no cualquier llanto, sus gritos ahuyentaban a perros y gatitos, sus l\u00e1grimas erosionaban la cantera del jard\u00edn de en frente de la helader\u00eda, pues ah\u00ed era desde donde Karina observaba su desgracia.<\/p>\n<p>\u00bfHas sentido que te hierbe la sangre? Yo tampoco, pero Karina justo en ese momento lo m\u00e1s que deseaba era salirse de su cuerpo, pues ella no cab\u00eda en s\u00ed misma, sus manos, sus piernas, su espalda, no pod\u00edan sostenerla, parec\u00eda que la sangre buscar\u00eda cualquier orificio para salir, nada faltaba para ver que de los o\u00eddos, Karina se escurr\u00eda gota a gota. Vivir en ella era lo peor que a cualquiera pudiera pasarle.<\/p>\n<p>\u00bfRecuerdas que te advert\u00ed lo peligroso que puede ser amar la perfecci\u00f3n?<\/p>\n<p>Yo no ten\u00eda miedo, hasta que vi a Karina, con los ojos zombificados, buscando en otros helados, miserias de perfecci\u00f3n, cachitos de suculenta y derretida perfecci\u00f3n, sobras, migajas de cerezosa perfecci\u00f3n, de kiwisosa perfecci\u00f3n. Y nada, no era suficiente, ni un poco, nada se le acercaba, nada era igual. Helados horribles y muy horribles, asquerosos helados, inconsistentes helados, obscenos helados, rugosos, vulgares, insolentes helados.<\/p>\n<p>La lengua de Karina era ahora la m\u00e1s triste de la ciudad, \u00a1nah!, del estado, del pa\u00eds, del mundo\u2026 el mundo.<\/p>\n<p>Photography by <a href=\"https:\/\/www.flickr.com\/photos\/bill_dane\/\">Bill Dane<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfHab\u00edas probado alguna vez helado m\u00e1s perfecto? Karina lo hab\u00eda hecho, el mejor helado de yogurt de la ciudad. \u00bfCiudad? \u00a1Nah!, del estado, del pa\u00eds, del mundo. Pod\u00edas ponerle cuantos aditivos quisieras y la combinaci\u00f3n favorita de aquella peque\u00f1a f\u00e9mina era; kiwi al fondo, cereza en medio y galleta de chocolate hecha polvo como cobertura. [&hellip;]<\/p>\n","protected":false},"author":6118,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7997],"tags":[7238],"class_list":["post-139363","post","type-post","status-publish","format-standard","hentry","category-textos","tag-abandono-tiempo"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La desaparici\u00f3n del Helado - ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/la-desaparicion-del-helado\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La desaparici\u00f3n del Helado - ERRR MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"\u00bfHab\u00edas probado alguna vez helado m\u00e1s perfecto? Karina lo hab\u00eda hecho, el mejor helado de yogurt de la ciudad. \u00bfCiudad? \u00a1Nah!, del estado, del pa\u00eds, del mundo. Pod\u00edas ponerle cuantos aditivos quisieras y la combinaci\u00f3n favorita de aquella peque\u00f1a f\u00e9mina era; kiwi al fondo, cereza en medio y galleta de chocolate hecha polvo como cobertura. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/la-desaparicion-del-helado\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-04T23:39:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T06:45:44+00:00\" \/>\n<meta name=\"author\" content=\"Omecalli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Omecalli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/\"},\"author\":{\"name\":\"Omecalli\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/d7c0d042fa164d173cd93c637b593170\"},\"headline\":\"La desaparici\u00f3n del Helado\",\"datePublished\":\"2018-11-04T23:39:09+00:00\",\"dateModified\":\"2022-08-31T06:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/\"},\"wordCount\":473,\"keywords\":[\"#abandono #tiempo\"],\"articleSection\":[\"Textos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/\",\"name\":\"La desaparici\u00f3n del Helado - ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"datePublished\":\"2018-11-04T23:39:09+00:00\",\"dateModified\":\"2022-08-31T06:45:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/d7c0d042fa164d173cd93c637b593170\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/la-desaparicion-del-helado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/errr-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La desaparici\u00f3n del Helado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/d7c0d042fa164d173cd93c637b593170\",\"name\":\"Omecalli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62dbd36695aa495a185cce0f3239f2796de4484b38d9066959392b5b73a8f1f0?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62dbd36695aa495a185cce0f3239f2796de4484b38d9066959392b5b73a8f1f0?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62dbd36695aa495a185cce0f3239f2796de4484b38d9066959392b5b73a8f1f0?s=96&d=identicon&r=g\",\"caption\":\"Omecalli\"},\"description\":\"Muchacha de colores y zapatos c\u00f3modos para bailar. De boca impertinente, temerosa y tartamuda. Cabellos necios y chamuscados. Nunca musa.\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/english\\\/author\\\/mitziohh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La desaparici\u00f3n del Helado - ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/la-desaparicion-del-helado\/","og_locale":"en_US","og_type":"article","og_title":"La desaparici\u00f3n del Helado - ERRR MAGAZINE","og_description":"\u00bfHab\u00edas probado alguna vez helado m\u00e1s perfecto? Karina lo hab\u00eda hecho, el mejor helado de yogurt de la ciudad. \u00bfCiudad? \u00a1Nah!, del estado, del pa\u00eds, del mundo. Pod\u00edas ponerle cuantos aditivos quisieras y la combinaci\u00f3n favorita de aquella peque\u00f1a f\u00e9mina era; kiwi al fondo, cereza en medio y galleta de chocolate hecha polvo como cobertura. [&hellip;]","og_url":"https:\/\/errr-magazine.com\/english\/la-desaparicion-del-helado\/","og_site_name":"ERRR MAGAZINE","article_published_time":"2018-11-04T23:39:09+00:00","article_modified_time":"2022-08-31T06:45:44+00:00","author":"Omecalli","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Omecalli","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/#article","isPartOf":{"@id":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/"},"author":{"name":"Omecalli","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/d7c0d042fa164d173cd93c637b593170"},"headline":"La desaparici\u00f3n del Helado","datePublished":"2018-11-04T23:39:09+00:00","dateModified":"2022-08-31T06:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/"},"wordCount":473,"keywords":["#abandono #tiempo"],"articleSection":["Textos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/","url":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/","name":"La desaparici\u00f3n del Helado - ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"datePublished":"2018-11-04T23:39:09+00:00","dateModified":"2022-08-31T06:45:44+00:00","author":{"@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/d7c0d042fa164d173cd93c637b593170"},"breadcrumb":{"@id":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/errr-magazine.com\/la-desaparicion-del-helado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/errr-magazine.com\/"},{"@type":"ListItem","position":2,"name":"La desaparici\u00f3n del Helado"}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/d7c0d042fa164d173cd93c637b593170","name":"Omecalli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/62dbd36695aa495a185cce0f3239f2796de4484b38d9066959392b5b73a8f1f0?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62dbd36695aa495a185cce0f3239f2796de4484b38d9066959392b5b73a8f1f0?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62dbd36695aa495a185cce0f3239f2796de4484b38d9066959392b5b73a8f1f0?s=96&d=identicon&r=g","caption":"Omecalli"},"description":"Girl of colors and comfortable shoes to dance. With an impertinent mouth, fearful and stuttering. Hair foolish and scorched. Never a muse.","url":"https:\/\/errr-magazine.com\/english\/author\/mitziohh\/"}]}},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":202892,"url":"https:\/\/errr-magazine.com\/english\/glaciar-libros-helados\/","url_meta":{"origin":139363,"position":0},"title":"Glacier: frozen books","author":"Glaciar: libros helados","date":"03\/22\/2026","format":false,"excerpt":"We realized that in our area there wasn\u2019t a place where you could buy books from independent publishers, contemporary Mexican women writers, art books, fanzines, and design and illustration items like stickers and prints.","rel":"","context":"In &quot;Librer\u00edas&quot;","block_context":{"text":"Librer\u00edas","link":"https:\/\/errr-magazine.com\/english\/category\/places\/librerias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/IMG_0227-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/IMG_0227-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/IMG_0227-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/IMG_0227-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/IMG_0227-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/IMG_0227-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":202646,"url":"https:\/\/errr-magazine.com\/english\/comprenderse-mejor\/","url_meta":{"origin":139363,"position":1},"title":"Understanding Oneself Better","author":"Karina Huizar","date":"03\/19\/2026","format":false,"excerpt":"I feel most like myself at sunset. I think sunset light is what attracts me most visually. The world around me becomes more vibrant and I feel more present. It\u2019s my favorite time to take photos.","rel":"","context":"In &quot;Personas&quot;","block_context":{"text":"Personas","link":"https:\/\/errr-magazine.com\/english\/category\/interviews\/personas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/image1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/image1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/image1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/image1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/image1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":205675,"url":"https:\/\/errr-magazine.com\/english\/la-matadora\/","url_meta":{"origin":139363,"position":2},"title":"La Matadora","author":"La Matadora","date":"04\/28\/2026","format":false,"excerpt":"The truth is that at the beginning we didn't have everything figured out \u2013money, structure, time\u2013 but we stopped waiting for ideal conditions and started making La Matadora work with what we did have: perseverance.","rel":"","context":"In &quot;Cafeterias y panader\u00edas&quot;","block_context":{"text":"Cafeterias y panader\u00edas","link":"https:\/\/errr-magazine.com\/english\/category\/places\/cafeterias-y-panaderias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/04\/3-1-scaled.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/04\/3-1-scaled.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/04\/3-1-scaled.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/04\/3-1-scaled.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/04\/3-1-scaled.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/04\/3-1-scaled.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":164143,"url":"https:\/\/errr-magazine.com\/english\/la-noche-mas-larga-del-ano\/","url_meta":{"origin":139363,"position":3},"title":"The longest night of the year","author":"Guillermo Orma","date":"12\/28\/2020","format":false,"excerpt":"No sab\u00eda c\u00f3mo empezar esto. Supongo que la mejor manera es hacerlo de la forma m\u00e1s honesta. Ya no eran buenos d\u00edas, todo se empez\u00f3 a caer, como caen las hojas en oto\u00f1o, o a\u00fan m\u00e1s, como caen los \u00e1ngeles cuando se enciende el cielo, cuando llueve y no hay\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/12\/Captura-de-pantalla-2020-12-28-a-las-17.18.29.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/12\/Captura-de-pantalla-2020-12-28-a-las-17.18.29.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/12\/Captura-de-pantalla-2020-12-28-a-las-17.18.29.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/12\/Captura-de-pantalla-2020-12-28-a-las-17.18.29.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2020\/12\/Captura-de-pantalla-2020-12-28-a-las-17.18.29.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":203274,"url":"https:\/\/errr-magazine.com\/english\/la-primera-vez-2\/","url_meta":{"origin":139363,"position":4},"title":"The First Time","author":"Raquel Del \u00c1ngel","date":"03\/30\/2026","format":false,"excerpt":"That first coffee that warmed your hands on a freezing morning in a city that, even before you knew its streets, had already named you one of its own.","rel":"","context":"In &quot;Narrativa&quot;","block_context":{"text":"Narrativa","link":"https:\/\/errr-magazine.com\/english\/category\/writing\/narrativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-SC-FEB26-08-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-SC-FEB26-08-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-SC-FEB26-08-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-SC-FEB26-08-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-SC-FEB26-08-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/Copia-de-SC-FEB26-08-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":202376,"url":"https:\/\/errr-magazine.com\/english\/agua-fria\/","url_meta":{"origin":139363,"position":5},"title":"Cold Water\u00a0","author":"Michelle Pulito Gonz\u00e1lez","date":"03\/15\/2026","format":false,"excerpt":"To rise and search for myself in the timeless waters, to carry myself always until I inhabit my body, to look the monster in the face and rescue myself from myself.","rel":"","context":"In &quot;Narrativa&quot;","block_context":{"text":"Narrativa","link":"https:\/\/errr-magazine.com\/english\/category\/writing\/narrativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/R1-00752-0005-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/R1-00752-0005-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/R1-00752-0005-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/R1-00752-0005-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/R1-00752-0005-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2026\/03\/R1-00752-0005-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"mfb_rest_fields":["title","yoast_head","yoast_head_json","jetpack_featured_media_url","jetpack-related-posts","jetpack_sharing_enabled"],"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/139363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/6118"}],"replies":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/comments?post=139363"}],"version-history":[{"count":4,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/139363\/revisions"}],"predecessor-version":[{"id":152351,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/139363\/revisions\/152351"}],"wp:attachment":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media?parent=139363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/categories?post=139363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/tags?post=139363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}