{"id":136091,"date":"2018-07-02T19:38:42","date_gmt":"2018-07-03T01:38:42","guid":{"rendered":"http:\/\/errr-magazine.com\/?p=136091"},"modified":"2022-08-31T01:53:06","modified_gmt":"2022-08-31T06:53:06","slug":"dos-ninos-en-casa","status":"publish","type":"post","link":"https:\/\/errr-magazine.com\/english\/dos-ninos-en-casa\/","title":{"rendered":"Dos ni\u00f1os en casa"},"content":{"rendered":"<p style=\"border: 0px; line-height: 1.6;\">En casa hay dos ni\u00f1os. Desde temprano se nota su presencia; despreocupados entran al ba\u00f1o y se tardan horas. Cuando por fin salen, es mejor esperar un poco antes de ingresar. Nunca prenden el boiler, pero siempre entran primero a ba\u00f1arse, y al salir, sin preguntar a nadie, deciden que lo mejor es apagarlo, no importando que falte por ba\u00f1arse toda la familia.<\/p>\n<p style=\"border: 0px; line-height: 1.6;\">No ayudan en las labores de la casa, se salen temprano y regresan pasando el mediod\u00eda. Exhaustos y con hambre, se ponen de malas al saber que a\u00fan no est\u00e1 la comida, prenden la televisi\u00f3n a volumen muy alto, van de un cuarto a otro buscando de qu\u00e9 quejarse, exasperan pero no auxilian ni dan cabida a opiniones. Para ellos, su verdad es absoluta.<\/p>\n<p style=\"border: 0px; line-height: 1.6;\">Son los primeros en sentarse, los \u00faltimos en terminar sus alimentos, recogen de vez en cuando sus trastes y disfrutan hacer sobremesa, platican y r\u00eden, son dos ni\u00f1os sin tantas preocupaciones.<\/p>\n<p style=\"border: 0px; line-height: 1.6;\">Hay d\u00edas en los que no amanecen tan bien, son m\u00e1s enojones de lo acostumbrado, toman sus medicinas con el ce\u00f1o fruncido, les cuesta andar y prefieren no salir a la calle; se la pasan largo rato dormidos o en cama, ni ganas tienen de quejarse, contestan grosero, pero en sus ojos existe explicaci\u00f3n a su mal humor, se refleja su malestar.<\/p>\n<p style=\"border: 0px; line-height: 1.6;\">En casa hay dos ni\u00f1os, una nena de 78 a\u00f1os y un varoncito de 80 a\u00f1os, en casa, estos ni\u00f1os son un verdadero desastre y dan ganas de darles sus nalgadas a cada berrinche y su jal\u00f3n de orejas a cada groser\u00eda o desatino. Pero agradezco al cielo que a\u00fan puedo disfrutar de sus travesuras.<\/p>\n<p>Photographers: <a href=\"https:\/\/www.snffnglu.com\/\">Sim Ouch<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>En casa hay dos ni\u00f1os. Desde temprano se nota su presencia; despreocupados entran al ba\u00f1o y se tardan horas. Cuando por fin salen, es mejor esperar un poco antes de ingresar. Nunca prenden el boiler, pero siempre entran primero a ba\u00f1arse, y al salir, sin preguntar a nadie, deciden que lo mejor es apagarlo, no [&hellip;]<\/p>\n","protected":false},"author":5828,"featured_media":136268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7997],"tags":[],"class_list":["post-136091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-textos"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dos ni\u00f1os en casa - ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/dos-ninos-en-casa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos ni\u00f1os en casa - ERRR MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"En casa hay dos ni\u00f1os. Desde temprano se nota su presencia; despreocupados entran al ba\u00f1o y se tardan horas. Cuando por fin salen, es mejor esperar un poco antes de ingresar. Nunca prenden el boiler, pero siempre entran primero a ba\u00f1arse, y al salir, sin preguntar a nadie, deciden que lo mejor es apagarlo, no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/dos-ninos-en-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-03T01:38:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T06:53:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guillermo Alvarado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillermo Alvarado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/\"},\"author\":{\"name\":\"Guillermo Alvarado\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/0ba0478c64cec13601464e0a5523f219\"},\"headline\":\"Dos ni\u00f1os en casa\",\"datePublished\":\"2018-07-03T01:38:42+00:00\",\"dateModified\":\"2022-08-31T06:53:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/\"},\"wordCount\":302,\"image\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/tumblr_p7s860yxb21qa2k9co1_1280.jpg\",\"articleSection\":[\"Textos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/\",\"name\":\"Dos ni\u00f1os en casa - ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/tumblr_p7s860yxb21qa2k9co1_1280.jpg\",\"datePublished\":\"2018-07-03T01:38:42+00:00\",\"dateModified\":\"2022-08-31T06:53:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/0ba0478c64cec13601464e0a5523f219\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/tumblr_p7s860yxb21qa2k9co1_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/errr-magazine.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/tumblr_p7s860yxb21qa2k9co1_1280.jpg\",\"width\":1280,\"height\":849},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/dos-ninos-en-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/errr-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos ni\u00f1os en casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/0ba0478c64cec13601464e0a5523f219\",\"name\":\"Guillermo Alvarado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/969a77431452af2428908e0cf2d950af3311a0f3310a3b8aaa2eac74e2a6c124?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/969a77431452af2428908e0cf2d950af3311a0f3310a3b8aaa2eac74e2a6c124?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/969a77431452af2428908e0cf2d950af3311a0f3310a3b8aaa2eac74e2a6c124?s=96&d=identicon&r=g\",\"caption\":\"Guillermo Alvarado\"},\"description\":\"Gusto de la lectura, en especial del cuento y del ensayo, disfruto del g\u00e9nero de ciencia ficci\u00f3n y de los c\u00f3mics. Comenc\u00e9 a escribir con el af\u00e1n de dar movimiento a las historias o ideas que se cruzan en mi vida y en mi imaginaci\u00f3n. Aqu\u00ed encontraran algunos cuentos y art\u00edculos m\u00edos. (mensualmente) http:\\\/\\\/jovenesconstruyendo.org\\\/ Aqu\u00ed breves ficciones (cuando me place) https:\\\/\\\/brickedsynecdoche.tumblr.com\\\/\",\"sameAs\":[\"http:\\\/\\\/jovenesconstruyendo.org\\\/\"],\"url\":\"https:\\\/\\\/errr-magazine.com\\\/english\\\/author\\\/macguffin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos ni\u00f1os en casa - ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/dos-ninos-en-casa\/","og_locale":"en_US","og_type":"article","og_title":"Dos ni\u00f1os en casa - ERRR MAGAZINE","og_description":"En casa hay dos ni\u00f1os. Desde temprano se nota su presencia; despreocupados entran al ba\u00f1o y se tardan horas. Cuando por fin salen, es mejor esperar un poco antes de ingresar. Nunca prenden el boiler, pero siempre entran primero a ba\u00f1arse, y al salir, sin preguntar a nadie, deciden que lo mejor es apagarlo, no [&hellip;]","og_url":"https:\/\/errr-magazine.com\/english\/dos-ninos-en-casa\/","og_site_name":"ERRR MAGAZINE","article_published_time":"2018-07-03T01:38:42+00:00","article_modified_time":"2022-08-31T06:53:06+00:00","og_image":[{"width":1280,"height":849,"url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg","type":"image\/jpeg"}],"author":"Guillermo Alvarado","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Guillermo Alvarado","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#article","isPartOf":{"@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/"},"author":{"name":"Guillermo Alvarado","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/0ba0478c64cec13601464e0a5523f219"},"headline":"Dos ni\u00f1os en casa","datePublished":"2018-07-03T01:38:42+00:00","dateModified":"2022-08-31T06:53:06+00:00","mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/"},"wordCount":302,"image":{"@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg","articleSection":["Textos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/","url":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/","name":"Dos ni\u00f1os en casa - ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#primaryimage"},"image":{"@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg","datePublished":"2018-07-03T01:38:42+00:00","dateModified":"2022-08-31T06:53:06+00:00","author":{"@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/0ba0478c64cec13601464e0a5523f219"},"breadcrumb":{"@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/dos-ninos-en-casa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#primaryimage","url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg","contentUrl":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg","width":1280,"height":849},{"@type":"BreadcrumbList","@id":"https:\/\/errr-magazine.com\/dos-ninos-en-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/errr-magazine.com\/"},{"@type":"ListItem","position":2,"name":"Dos ni\u00f1os en casa"}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/0ba0478c64cec13601464e0a5523f219","name":"Guillermo Alvarado","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/969a77431452af2428908e0cf2d950af3311a0f3310a3b8aaa2eac74e2a6c124?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/969a77431452af2428908e0cf2d950af3311a0f3310a3b8aaa2eac74e2a6c124?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/969a77431452af2428908e0cf2d950af3311a0f3310a3b8aaa2eac74e2a6c124?s=96&d=identicon&r=g","caption":"Guillermo Alvarado"},"description":"Gusto de la lectura, en especial del cuento y del ensayo, disfruto del g\u00e9nero de ciencia ficci\u00f3n y de los c\u00f3mics. Comenc\u00e9 a escribir con el af\u00e1n de dar movimiento a las historias o ideas que se cruzan en mi vida y en mi imaginaci\u00f3n. Aqu\u00ed encontraran algunos cuentos y art\u00edculos m\u00edos. (mensualmente) http:\/\/jovenesconstruyendo.org\/ Aqu\u00ed breves ficciones (cuando me place) https:\/\/brickedsynecdoche.tumblr.com\/","sameAs":["http:\/\/jovenesconstruyendo.org\/"],"url":"https:\/\/errr-magazine.com\/english\/author\/macguffin\/"}]}},"jetpack_featured_media_url":"https:\/\/errr-magazine.com\/wp-content\/uploads\/2018\/07\/tumblr_p7s860yxb21qa2k9co1_1280.jpg","jetpack-related-posts":[{"id":135873,"url":"https:\/\/errr-magazine.com\/english\/parangacutirimicuaro\/","url_meta":{"origin":136091,"position":0},"title":"Parangacutirimicuaro","author":"Anantli Pallares","date":"07\/01\/2018","format":false,"excerpt":"Ya hace c\u00f3mo que te gustan, unos 3 a\u00f1os desde que romp\u00ed con la Romis y pues dije ta bien, ya es hora de salir con alguien m\u00e1s. Conoc\u00ed a la Laura una morra centrada, buen pedo y guap\u00edsima. Despu\u00e9s de 8 meses saliendo, decidimos ir a vivir juntos. La\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/06\/30920897763_561708316b_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/06\/30920897763_561708316b_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/06\/30920897763_561708316b_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/06\/30920897763_561708316b_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/06\/30920897763_561708316b_o.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/06\/30920897763_561708316b_o.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":136812,"url":"https:\/\/errr-magazine.com\/english\/las-habichuelas-de-juan\/","url_meta":{"origin":136091,"position":1},"title":"Las habichuelas de Juan","author":"Jos\u00e9 Luis Bobadilla","date":"09\/05\/2019","format":false,"excerpt":"No hubo nunca nada para Juan m\u00e1s importante que sus habichuelas.\u00a0Desde ni\u00f1o las cuid\u00f3 con esmero y ansiedad, evitando que nada las maltratara. La atesor\u00f3\u00a0como nada en el universo entero a cambio pr\u00e1cticamente de nada. Juan era torpe y nervioso y eso le impidi\u00f3 usarlas como se deb\u00eda. Ah\u00ed las\u2026","rel":"","context":"In &quot;Writing&quot;","block_context":{"text":"Writing","link":"https:\/\/errr-magazine.com\/english\/category\/writing\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2022\/06\/37669444316_8f049d5268_b.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2022\/06\/37669444316_8f049d5268_b.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2022\/06\/37669444316_8f049d5268_b.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2022\/06\/37669444316_8f049d5268_b.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":141284,"url":"https:\/\/errr-magazine.com\/english\/the-velvet-underground-mico\/","url_meta":{"origin":136091,"position":2},"title":"The Velvet Underground &amp; Mico","author":"\u00c1ngel Armenta L\u00f3pez","date":"03\/05\/2019","format":false,"excerpt":"Nos echaron de todas las cantinas de Rep\u00fablica de Cuba, en Garibaldi, hubo una balacera con 2 muertitos, los federales, no nos dejaron pasar. En Isabel la Cat\u00f3lica, todo era demasiado caro. Se nos agotaban los lugares para seguir bebiendo, y yo, yo no pod\u00eda dejar pasar esa noche sin\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/02\/20470123200_4d0058c449_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/02\/20470123200_4d0058c449_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/02\/20470123200_4d0058c449_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2019\/02\/20470123200_4d0058c449_o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":133504,"url":"https:\/\/errr-magazine.com\/english\/selfie-de-mama-millenial\/","url_meta":{"origin":136091,"position":3},"title":"selfie de mam\u00e1 millenial","author":"Anait\u00e9 Ancira","date":"09\/15\/2019","format":false,"excerpt":"la primera vez que fui mam\u00e1 todo sucedi\u00f3 en un hilo no hab\u00eda nadie s\u00f3lo mi hijo y yo un amor tit\u00e1nico y el instinto de supervivencia ahora soy mam\u00e1 por segunda vez en la era millenial pero no soy millenial o al menos no por fecha de nacimiento me\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/05\/11_01770009-copy.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/05\/11_01770009-copy.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/05\/11_01770009-copy.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2018\/05\/11_01770009-copy.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":154318,"url":"https:\/\/errr-magazine.com\/english\/worlds-greatest-dad\/","url_meta":{"origin":136091,"position":4},"title":"World&#8217;s greatest dad","author":"Paulina Parra","date":"02\/03\/2019","format":false,"excerpt":"Cuando nac\u00ed pes\u00e9 poco m\u00e1s de un kilogramo, era peque\u00f1a y muy fr\u00e1gil. Mi pap\u00e1 dice que ten\u00eda las manos chiquitas y flaquitas, los guantecitos que mi abuela teji\u00f3 para m\u00ed se me resbalaban al tenerlos puestos. Mi madre tuvo un episodio fuert\u00edsimo de algo llamado depresi\u00f3n post parto, durante\u2026","rel":"","context":"In &quot;Textos&quot;","block_context":{"text":"Textos","link":"https:\/\/errr-magazine.com\/english\/category\/textos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":168764,"url":"https:\/\/errr-magazine.com\/english\/que-el-mundo-explote-de-repente-sin-avisarnos\/","url_meta":{"origin":136091,"position":5},"title":"Que el mundo explote de repente, sin avisarnos","author":"Rodrigo Solano","date":"03\/16\/2021","format":false,"excerpt":"Posteriormente, una semana despu\u00e9s, hicimos las fotos en el departamento de ellos, yo pas\u00e9 a comprar previamente ciertos props que utilizar\u00edamos para la sesi\u00f3n, entre ellos un pescado que hab\u00eda pasado a comprar al mercado de Xochimilco por $60 pesos...","rel":"","context":"In &quot;Interview&quot;","block_context":{"text":"Interview","link":"https:\/\/errr-magazine.com\/english\/category\/interviews\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2021\/03\/imagen-31.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2021\/03\/imagen-31.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2021\/03\/imagen-31.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2021\/03\/imagen-31.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/errr-magazine.com\/wp-content\/uploads\/2021\/03\/imagen-31.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"mfb_rest_fields":["title","yoast_head","yoast_head_json","jetpack_featured_media_url","jetpack-related-posts","jetpack_sharing_enabled"],"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/136091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/5828"}],"replies":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/comments?post=136091"}],"version-history":[{"count":5,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/136091\/revisions"}],"predecessor-version":[{"id":136291,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/136091\/revisions\/136291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media\/136268"}],"wp:attachment":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media?parent=136091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/categories?post=136091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/tags?post=136091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}