{"id":127549,"date":"2018-01-19T19:01:24","date_gmt":"2018-01-20T01:01:24","guid":{"rendered":"http:\/\/errr-magazine.com\/?p=127549"},"modified":"2022-08-31T02:04:37","modified_gmt":"2022-08-31T07:04:37","slug":"el-loco","status":"publish","type":"post","link":"https:\/\/errr-magazine.com\/english\/el-loco\/","title":{"rendered":"El loco"},"content":{"rendered":"<p>Realizo mi ejercicio matutino de introspecci\u00f3n. Me demoro 5 minutos m\u00e1s de lo usual, he venido sintiendo un vac\u00edo en el pecho, a un costado del \u00f3rgano vital. Parece lleno de aire, una peque\u00f1a burbuja a punto de reventar, \u00bfqu\u00e9 ser\u00e1?<\/p>\n<p>Exhalo, inhalo, exhalo, inhalo. Repito. El dolor no aparece, pero la sensaci\u00f3n persiste, se expande en mi interior, me sofoca por dentro.<\/p>\n<p>Miro por la ventana, a\u00fan con la ausencia en el centro.<br \/>\nEl panorama urbano no tiene lo que necesito, algo hace falta.<br \/>\n\u201cSer\u00e1 otro d\u00eda largo\u201d. Suspiro.<br \/>\nObservo las paredes de la habitaci\u00f3n. Los jirones de papel mal arrancados a\u00fan cuelgan de ella balance\u00e1ndose con la fina brisa que entra por una rendija de la ventana.<br \/>\nYa no hay cuadros en ella, ni adornos innecesarios, pero los agujeros y clavos que los sosten\u00edan permanecen como un cruel recordatorio de aquello que se ha ido.<\/p>\n<p>No lloro, porque me estoy acostumbrando a la ausencia, pese al hueco en el costado izquierdo y las n\u00e1useas interminables.<\/p>\n<p>El malestar del pecho comienza a subir a mi cabeza, mi respiraci\u00f3n se agita, mi desesperaci\u00f3n crece. Busco un punto donde fijar mi vista, donde perder mi mente.<br \/>\nUna peque\u00f1a ave, posada en el marco de la ventana, una paloma, tal vez otra cosa.<br \/>\nColores pardos, grises.<br \/>\nMe tranquilizo.<br \/>\nUna leve luz toca el plumaje, un destello de rojo, \u00bftal vez una ilusi\u00f3n? No, seguro que ha sucedido, me repito.<br \/>\nY me duele, te recuerdo y me quiebro por dentro.<br \/>\nRojo, como el su\u00e9ter tejido que se ajustaba tan bien a tu figura.<br \/>\nDorado, como el destello de tu cabello por la ma\u00f1ana.<br \/>\nY el carmes\u00ed se torna negro y en tu ausencia consigues romperme de nuevo.<\/p>\n<p>Photographers: <a href=\"https:\/\/www.flickr.com\/photos\/chocapic\/\" rel=\"noopener\" target=\"_blank\">Tom\u00e9 Duarte<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Realizo mi ejercicio matutino de introspecci\u00f3n. Me demoro 5 minutos m\u00e1s de lo usual, he venido sintiendo un vac\u00edo en el pecho, a un costado del \u00f3rgano vital. Parece lleno de aire, una peque\u00f1a burbuja a punto de reventar, \u00bfqu\u00e9 ser\u00e1? Exhalo, inhalo, exhalo, inhalo. Repito. El dolor no aparece, pero la sensaci\u00f3n persiste, se [&hellip;]<\/p>\n","protected":false},"author":5144,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17385],"tags":[],"class_list":["post-127549","post","type-post","status-publish","format-standard","hentry","category-writing"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El loco - ERRR MAGAZINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/errr-magazine.com\/english\/el-loco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El loco - ERRR MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"Realizo mi ejercicio matutino de introspecci\u00f3n. Me demoro 5 minutos m\u00e1s de lo usual, he venido sintiendo un vac\u00edo en el pecho, a un costado del \u00f3rgano vital. Parece lleno de aire, una peque\u00f1a burbuja a punto de reventar, \u00bfqu\u00e9 ser\u00e1? Exhalo, inhalo, exhalo, inhalo. Repito. El dolor no aparece, pero la sensaci\u00f3n persiste, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/errr-magazine.com\/english\/el-loco\/\" \/>\n<meta property=\"og:site_name\" content=\"ERRR MAGAZINE\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-20T01:01:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T07:04:37+00:00\" \/>\n<meta name=\"author\" content=\"Dai W\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dai W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/\"},\"author\":{\"name\":\"Dai W\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/c2a63851e2b811d694339320fe99720b\"},\"headline\":\"El loco\",\"datePublished\":\"2018-01-20T01:01:24+00:00\",\"dateModified\":\"2022-08-31T07:04:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/\"},\"wordCount\":307,\"articleSection\":[\"Writing\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/\",\"name\":\"El loco - ERRR MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\"},\"datePublished\":\"2018-01-20T01:01:24+00:00\",\"dateModified\":\"2022-08-31T07:04:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/c2a63851e2b811d694339320fe99720b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/el-loco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/errr-magazine.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El loco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#website\",\"url\":\"https:\\\/\\\/errr-magazine.com\\\/\",\"name\":\"ERRR MAGAZINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/errr-magazine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/errr-magazine.com\\\/#\\\/schema\\\/person\\\/c2a63851e2b811d694339320fe99720b\",\"name\":\"Dai W\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdd37b76ed4f56603230fb097797a9e5a59d01ed606709e284247f43e77acb22?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdd37b76ed4f56603230fb097797a9e5a59d01ed606709e284247f43e77acb22?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdd37b76ed4f56603230fb097797a9e5a59d01ed606709e284247f43e77acb22?s=96&d=identicon&r=g\",\"caption\":\"Dai W\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/daitoodd\"],\"url\":\"https:\\\/\\\/errr-magazine.com\\\/english\\\/author\\\/daitoodd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El loco - ERRR MAGAZINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/errr-magazine.com\/english\/el-loco\/","og_locale":"en_US","og_type":"article","og_title":"El loco - ERRR MAGAZINE","og_description":"Realizo mi ejercicio matutino de introspecci\u00f3n. Me demoro 5 minutos m\u00e1s de lo usual, he venido sintiendo un vac\u00edo en el pecho, a un costado del \u00f3rgano vital. Parece lleno de aire, una peque\u00f1a burbuja a punto de reventar, \u00bfqu\u00e9 ser\u00e1? Exhalo, inhalo, exhalo, inhalo. Repito. El dolor no aparece, pero la sensaci\u00f3n persiste, se [&hellip;]","og_url":"https:\/\/errr-magazine.com\/english\/el-loco\/","og_site_name":"ERRR MAGAZINE","article_published_time":"2018-01-20T01:01:24+00:00","article_modified_time":"2022-08-31T07:04:37+00:00","author":"Dai W","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dai W","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/errr-magazine.com\/el-loco\/#article","isPartOf":{"@id":"https:\/\/errr-magazine.com\/el-loco\/"},"author":{"name":"Dai W","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/c2a63851e2b811d694339320fe99720b"},"headline":"El loco","datePublished":"2018-01-20T01:01:24+00:00","dateModified":"2022-08-31T07:04:37+00:00","mainEntityOfPage":{"@id":"https:\/\/errr-magazine.com\/el-loco\/"},"wordCount":307,"articleSection":["Writing"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/errr-magazine.com\/el-loco\/","url":"https:\/\/errr-magazine.com\/el-loco\/","name":"El loco - ERRR MAGAZINE","isPartOf":{"@id":"https:\/\/errr-magazine.com\/#website"},"datePublished":"2018-01-20T01:01:24+00:00","dateModified":"2022-08-31T07:04:37+00:00","author":{"@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/c2a63851e2b811d694339320fe99720b"},"breadcrumb":{"@id":"https:\/\/errr-magazine.com\/el-loco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/errr-magazine.com\/el-loco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/errr-magazine.com\/el-loco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/errr-magazine.com\/"},{"@type":"ListItem","position":2,"name":"El loco"}]},{"@type":"WebSite","@id":"https:\/\/errr-magazine.com\/#website","url":"https:\/\/errr-magazine.com\/","name":"ERRR MAGAZINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/errr-magazine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/errr-magazine.com\/#\/schema\/person\/c2a63851e2b811d694339320fe99720b","name":"Dai W","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/bdd37b76ed4f56603230fb097797a9e5a59d01ed606709e284247f43e77acb22?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdd37b76ed4f56603230fb097797a9e5a59d01ed606709e284247f43e77acb22?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdd37b76ed4f56603230fb097797a9e5a59d01ed606709e284247f43e77acb22?s=96&d=identicon&r=g","caption":"Dai W"},"sameAs":["https:\/\/www.facebook.com\/daitoodd"],"url":"https:\/\/errr-magazine.com\/english\/author\/daitoodd\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"mfb_rest_fields":["title","yoast_head","yoast_head_json","jetpack_featured_media_url","jetpack_sharing_enabled"],"_links":{"self":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/127549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/users\/5144"}],"replies":[{"embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/comments?post=127549"}],"version-history":[{"count":5,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/127549\/revisions"}],"predecessor-version":[{"id":127874,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/posts\/127549\/revisions\/127874"}],"wp:attachment":[{"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/media?parent=127549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/categories?post=127549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/errr-magazine.com\/english\/wp-json\/wp\/v2\/tags?post=127549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}